{"id":17075,"date":"2025-05-15T20:07:50","date_gmt":"2025-05-15T18:07:50","guid":{"rendered":"https:\/\/poppersparadise.eu\/?post_type=product&#038;p=17075"},"modified":"2026-07-31T15:31:37","modified_gmt":"2026-07-31T13:31:37","slug":"popper-le-jus-amyl-10ml-2","status":"publish","type":"product","link":"https:\/\/poppersparadise.eu\/it\/product\/le-jus-amyl-10ml-poppers\/","title":{"rendered":"Le Jus Amyl 10ml"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Popper Le Jus Amyl 10ml - compatto, potente e classico<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il popper Le Jus Amyl 10ml \u00e8 la scelta ideale per gli amanti degli aromi classici Amyl. Con una formula potente e dimensioni compatte, questo prodotto offre un'esperienza di fragranza intensa, perfetta per i momenti speciali. Prodotto in Belgio secondo elevati standard di qualit\u00e0, \u00e8 una parte fidata e amata della linea di prodotti Le Jus.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Caratteristiche principali di Le Jus Amyl<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Formula potente<\/strong>: Contiene Amyl per una diffusione intensa e duratura della fragranza.<\/li>\n\n\n\n<li><strong>Dimensioni compatte<\/strong>: Pratico flacone da 10 ml, ideale da portare con s\u00e9.<\/li>\n\n\n\n<li><strong>Alta qualit\u00e0<\/strong>Prodotto in Belgio secondo rigorosi standard di qualit\u00e0.<\/li>\n\n\n\n<li><strong>Prodotto popolare<\/strong>Fa parte dell'apprezzata linea di prodotti Le Jus.<\/li>\n\n\n\n<li><strong>Perfetto per gli appassionati<\/strong>: Specialmente per gli appassionati delle fragranze classiche Amyl.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Come utilizzare Le Jus Amyl?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Utilizzare Le Jus Amyl solo come disperdente di fragranze o solvente per la pulizia. Non \u00e8 adatto al consumo umano e non deve essere inalato. Conservare il prodotto in un luogo fresco e asciutto e chiudere bene il flacone dopo l'uso.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Perch\u00e9 Le Jus Amyl \u00e8 uno dei preferiti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La sua formula potente, la confezione compatta e la qualit\u00e0 affidabile rendono questo prodotto uno dei preferiti dagli appassionati di diffusori di fragranze. Offre un'esperienza di fragranza intensa, perfetta per i momenti speciali.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Avvertenze<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Liquido e vapore altamente infiammabili (H225).<br>Provoca irritazione cutanea e oculare (H315\/H319).<br>Tossico per inalazione (H331).<br>Non \u00e8 un farmaco. Usare a proprio rischio e pericolo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Utilizzo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 inteso solo come diffusore di fragranze o solvente per la pulizia.<br>Non \u00e8 adatto al consumo umano e non deve essere inalato.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Immagazzinamento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Conservare in un luogo fresco e asciutto. Tenere fuori dalla portata dei bambini.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Paese di origine<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Belgio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p><strong><br \/>ACCESSORI COMPATIBILI:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/poppersparadise.eu\/it\/categoria-di-prodotto\/accessori\/annusatori-piccoli\/\">Fiuto Piccolo<\/a><\/li>\n<li><a href=\"https:\/\/poppersparadise.eu\/it\/prodotto\/xtrm-poppers-houder-zwart-small\/\">XTRM Poppers Supporto Piccolo<\/a><\/li>\n<li><a href=\"https:\/\/poppersparadise.eu\/it\/prodotto\/poppers-xtrm-keeper-small-10ml-2\/\">XTRM Poppers Custode Piccolo<\/a><\/li>\n<\/ul>","protected":false},"featured_media":17076,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[746],"product_cat":[34],"product_tag":[],"class_list":["post-17075","product","type-product","status-publish","has-post-thumbnail","product_brand-le-jus","product_cat-kleine-flesjes-poppers","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"df_price":6.5,"df_sale_price":"","df_regular_price":6.5,"df_image_link":"https:\/\/poppersparadise.eu\/wp-content\/uploads\/2025\/05\/Le-Jus-Amyle-Base-10ml-300x300.jpg","_links":{"self":[{"href":"https:\/\/poppersparadise.eu\/it\/wp-json\/wp\/v2\/product\/17075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poppersparadise.eu\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/poppersparadise.eu\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/poppersparadise.eu\/it\/wp-json\/wp\/v2\/comments?post=17075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poppersparadise.eu\/it\/wp-json\/wp\/v2\/media\/17076"}],"wp:attachment":[{"href":"https:\/\/poppersparadise.eu\/it\/wp-json\/wp\/v2\/media?parent=17075"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/poppersparadise.eu\/it\/wp-json\/wp\/v2\/product_brand?post=17075"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/poppersparadise.eu\/it\/wp-json\/wp\/v2\/product_cat?post=17075"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/poppersparadise.eu\/it\/wp-json\/wp\/v2\/product_tag?post=17075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}